{"id":3506,"date":"2024-11-15T17:31:52","date_gmt":"2024-11-15T17:31:52","guid":{"rendered":"https:\/\/sankhamtech.com\/index.php\/content\/india\/english\/home\/free-courses\/mastering-css-essential-concepts-for-web-design\/try-solving-this-to-better-understand-flexbox\/"},"modified":"2024-11-15T17:32:37","modified_gmt":"2024-11-15T17:32:37","slug":"try-solving-this-to-better-understand-flexbox","status":"publish","type":"page","link":"https:\/\/sankhamtech.com\/index.php\/content\/in\/en\/home\/free-courses\/mastering-css-essential-concepts-for-web-design\/try-solving-this-to-better-understand-flexbox\/","title":{"rendered":"Try Solving This to Better Understand FLEXBOX"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"3506\" class=\"elementor elementor-3506\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b8912ad e-flex e-con-boxed e-con e-parent\" data-id=\"b8912ad\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-a3aba31 e-con-full e-flex e-con e-child\" data-id=\"a3aba31\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5093309 elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"5093309\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h6 style=\"text-align: center;\"><span style=\"text-decoration: underline;\">Lessons<\/span><\/h6>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b4801a8 elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-text-editor\" data-id=\"b4801a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h6 style=\"text-align: center;\"><a href=\"https:\/\/sankhamtech.com\/index.php\/content\/india\/english\/home\/free-courses\/mastering-css-essential-concepts-for-web-design\/\"><span style=\"text-decoration: underline;\">Lessons<\/span><\/a><\/h6>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f274502 elementor-hidden-mobile elementor-widget elementor-widget-darsanam_header_menu_widget\" data-id=\"f274502\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"darsanam_header_menu_widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"darsanam-menu-wrapper \"><div class='hamburger-icon'><i class=\"fas fa-grip-lines\"><\/i> &nbsp; <\/div><div class=\"menu-container\"><nav class='elementor-menu'><ul class='darsanam-menu-vertical'><li class='darsanam-menu-item'><a href='https:\/\/sankhamtech.com\/index.php\/content\/in\/en\/home\/free-courses\/mastering-css-essential-concepts-for-web-design\/why-when-to-use-which-css-style\/'>Why & When to Use Which CSS Style<\/a><i class=\"menu-icon-right fas fa-angle-right\"><\/i><\/li><li class='darsanam-menu-item'><a href='https:\/\/sankhamtech.com\/index.php\/content\/in\/en\/home\/free-courses\/mastering-css-essential-concepts-for-web-design\/how-css-padding-margin-height-width-works\/'>How CSS Padding, Margin, Height, Width Works<\/a><i class=\"menu-icon-right fas fa-angle-right\"><\/i><\/li><li class='darsanam-menu-item'><a href='https:\/\/sankhamtech.com\/index.php\/content\/in\/en\/home\/free-courses\/mastering-css-essential-concepts-for-web-design\/positioning-html-elements-using-css\/'>Positioning HTML Elements Using CSS<\/a><i class=\"menu-icon-right fas fa-angle-right\"><\/i><\/li><li class='darsanam-menu-item'><a href='https:\/\/sankhamtech.com\/index.php\/content\/in\/en\/home\/free-courses\/mastering-css-essential-concepts-for-web-design\/text-align-margin-auto-transform-translate-css-property\/'>Text-Align, Margin Auto, Transform Translate CSS Property<\/a><i class=\"menu-icon-right fas fa-angle-right\"><\/i><\/li><li class='darsanam-menu-item'><a href='https:\/\/sankhamtech.com\/index.php\/content\/in\/en\/home\/free-courses\/mastering-css-essential-concepts-for-web-design\/introduction-to-layouts-flexbox-grid\/'>Introduction to Layouts (FLEXBOX & GRID)<\/a><i class=\"menu-icon-right fas fa-angle-right\"><\/i><\/li><li class='darsanam-menu-item'><a href='https:\/\/sankhamtech.com\/index.php\/content\/in\/en\/home\/free-courses\/mastering-css-essential-concepts-for-web-design\/horizontal-alignment-using-flexbox\/'>HORIZONTAL ALIGNMENT USING FLEXBOX<\/a><i class=\"menu-icon-right fas fa-angle-right\"><\/i><\/li><li class='darsanam-menu-item'><a href='https:\/\/sankhamtech.com\/index.php\/content\/in\/en\/home\/free-courses\/mastering-css-essential-concepts-for-web-design\/horizantal-vertical-alignment-with-flexbox\/'>HORIZANTAL & VERTICAL ALIGNMENT With FLEXBOX<\/a><i class=\"menu-icon-right fas fa-angle-right\"><\/i><\/li><li class='darsanam-menu-item'><a href='https:\/\/sankhamtech.com\/index.php\/content\/in\/en\/home\/free-courses\/mastering-css-essential-concepts-for-web-design\/understanding-justify-content-align-item-properties-of-flexbox\/'>Understanding JUSTIFY-CONTENT & ALIGN-ITEM Properties of FLEXBOX<\/a><i class=\"menu-icon-right fas fa-angle-right\"><\/i><\/li><li class='darsanam-menu-item'><a href='https:\/\/sankhamtech.com\/index.php\/content\/in\/en\/home\/free-courses\/mastering-css-essential-concepts-for-web-design\/try-solving-this-to-better-understand-flexbox\/' style='color: #FF7700 !important'>Try Solving This to Better Understand FLEXBOX<\/a><i class=\"menu-icon-right fas fa-angle-right\"><\/i><\/li><li class='darsanam-menu-item'><a href='https:\/\/sankhamtech.com\/index.php\/content\/in\/en\/home\/free-courses\/mastering-css-essential-concepts-for-web-design\/css-grid-layouts-simplified\/'>CSS GRID LAYOUTS Simplified<\/a><i class=\"menu-icon-right fas fa-angle-right\"><\/i><\/li><\/ul><\/nav><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5f68e23 e-con-full e-flex e-con e-child\" data-id=\"5f68e23\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e5c89a9 elementor-widget elementor-widget-text-editor\" data-id=\"e5c89a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Try Solving This to Better Understand FLEXBOX<\/h2><p><\/p><p><\/p><p><\/p><p><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-688b71a elementor-widget elementor-widget-video\" data-id=\"688b71a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/Ye3o9vDGanU?list=PL5l69Ui6w3V90OzAM3sqapvln-2MWCwO-&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ad620a4 elementor-widget elementor-widget-text-editor\" data-id=\"ad620a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Challenge your Flexbox skills with our engaging tutorial, &#8216;Try Solving This to Better Understand FLEXBOX&#8217;. Designed for web developers and designers at all levels, this video presents a unique, hands-on approach to mastering Flexbox. Dive into a practical challenge that will test and improve your understanding of Flexbox&#8217;s capabilities in real-world scenarios. This interactive experience not only reinforces your existing knowledge but also introduces new techniques and strategies in CSS layout management. By solving the given task, you&#8217;ll gain a deeper insight into how Flexbox works and how to leverage it for more effective and responsive web designs. Whether you&#8217;re a beginner looking to learn through practice or a seasoned developer aiming to refine your skills, this tutorial is the perfect way to enhance your Flexbox proficiency. Accept the challenge and elevate your web design game with Flexbox!<\/p><p><!-- \/wp:paragraph --><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Lessons Lessons &nbsp; Why &#038; When to Use Which CSS Style How CSS Padding, Margin, Height, Width Works Positioning HTML Elements Using CSS Text-Align, Margin Auto, Transform Translate CSS Property Introduction to Layouts (FLEXBOX &#038; GRID) HORIZONTAL ALIGNMENT USING FLEXBOX HORIZANTAL &#038; VERTICAL ALIGNMENT With FLEXBOX Understanding JUSTIFY-CONTENT &#038; ALIGN-ITEM Properties of FLEXBOX Try Solving [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":3442,"menu_order":8,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-3506","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Try Solving This to Better Understand FLEXBOX - Sankham Technologies<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sankhamtech.com\/index.php\/content\/in\/en\/home\/free-courses\/mastering-css-essential-concepts-for-web-design\/try-solving-this-to-better-understand-flexbox\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Try Solving This to Better Understand FLEXBOX - Sankham Technologies\" \/>\n<meta property=\"og:description\" content=\"Lessons Lessons &nbsp; Why &#038; When to Use Which CSS Style How CSS Padding, Margin, Height, Width Works Positioning HTML Elements Using CSS Text-Align, Margin Auto, Transform Translate CSS Property Introduction to Layouts (FLEXBOX &#038; GRID) HORIZONTAL ALIGNMENT USING FLEXBOX HORIZANTAL &#038; VERTICAL ALIGNMENT With FLEXBOX Understanding JUSTIFY-CONTENT &#038; ALIGN-ITEM Properties of FLEXBOX Try Solving [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sankhamtech.com\/index.php\/content\/in\/en\/home\/free-courses\/mastering-css-essential-concepts-for-web-design\/try-solving-this-to-better-understand-flexbox\/\" \/>\n<meta property=\"og:site_name\" content=\"Sankham Technologies\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-15T17:32:37+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sankhamtech.com\\\/index.php\\\/content\\\/in\\\/en\\\/home\\\/free-courses\\\/mastering-css-essential-concepts-for-web-design\\\/try-solving-this-to-better-understand-flexbox\\\/\",\"url\":\"https:\\\/\\\/sankhamtech.com\\\/index.php\\\/content\\\/in\\\/en\\\/home\\\/free-courses\\\/mastering-css-essential-concepts-for-web-design\\\/try-solving-this-to-better-understand-flexbox\\\/\",\"name\":\"Try Solving This to Better Understand FLEXBOX - Sankham Technologies\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sankhamtech.com\\\/#website\"},\"datePublished\":\"2024-11-15T17:31:52+00:00\",\"dateModified\":\"2024-11-15T17:32:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sankhamtech.com\\\/index.php\\\/content\\\/in\\\/en\\\/home\\\/free-courses\\\/mastering-css-essential-concepts-for-web-design\\\/try-solving-this-to-better-understand-flexbox\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sankhamtech.com\\\/index.php\\\/content\\\/in\\\/en\\\/home\\\/free-courses\\\/mastering-css-essential-concepts-for-web-design\\\/try-solving-this-to-better-understand-flexbox\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sankhamtech.com\\\/index.php\\\/content\\\/in\\\/en\\\/home\\\/free-courses\\\/mastering-css-essential-concepts-for-web-design\\\/try-solving-this-to-better-understand-flexbox\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sankhamtech.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Content\",\"item\":\"https:\\\/\\\/sankhamtech.com\\\/index.php\\\/content\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"India\",\"item\":\"https:\\\/\\\/sankhamtech.com\\\/index.php\\\/content\\\/in\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"English\",\"item\":\"https:\\\/\\\/sankhamtech.com\\\/index.php\\\/content\\\/in\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sankhamtech.com\\\/\"},{\"@type\":\"ListItem\",\"position\":6,\"name\":\"Free Courses\",\"item\":\"https:\\\/\\\/sankhamtech.com\\\/index.php\\\/content\\\/in\\\/en\\\/home\\\/free-courses\\\/\"},{\"@type\":\"ListItem\",\"position\":7,\"name\":\"Mastering CSS: Essential Concepts for Web Design\",\"item\":\"https:\\\/\\\/sankhamtech.com\\\/indexphp\\\/content\\\/in\\\/en\\\/home\\\/free-courses\\\/mastering-css-essential-concepts-for-web-design\\\/\"},{\"@type\":\"ListItem\",\"position\":8,\"name\":\"Try Solving This to Better Understand FLEXBOX\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sankhamtech.com\\\/#website\",\"url\":\"https:\\\/\\\/sankhamtech.com\\\/\",\"name\":\"Sankham Technologies\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/sankhamtech.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sankhamtech.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sankhamtech.com\\\/#organization\",\"name\":\"Sankham Technologies\",\"url\":\"https:\\\/\\\/sankhamtech.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/sankhamtech.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sankhamtech.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Logo-Dark-1.png\",\"contentUrl\":\"https:\\\/\\\/sankhamtech.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Logo-Dark-1.png\",\"width\":306,\"height\":74,\"caption\":\"Sankham Technologies\"},\"image\":{\"@id\":\"https:\\\/\\\/sankhamtech.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Try Solving This to Better Understand FLEXBOX - Sankham Technologies","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sankhamtech.com\/index.php\/content\/in\/en\/home\/free-courses\/mastering-css-essential-concepts-for-web-design\/try-solving-this-to-better-understand-flexbox\/","og_locale":"en_US","og_type":"article","og_title":"Try Solving This to Better Understand FLEXBOX - Sankham Technologies","og_description":"Lessons Lessons &nbsp; Why &#038; When to Use Which CSS Style How CSS Padding, Margin, Height, Width Works Positioning HTML Elements Using CSS Text-Align, Margin Auto, Transform Translate CSS Property Introduction to Layouts (FLEXBOX &#038; GRID) HORIZONTAL ALIGNMENT USING FLEXBOX HORIZANTAL &#038; VERTICAL ALIGNMENT With FLEXBOX Understanding JUSTIFY-CONTENT &#038; ALIGN-ITEM Properties of FLEXBOX Try Solving [&hellip;]","og_url":"https:\/\/sankhamtech.com\/index.php\/content\/in\/en\/home\/free-courses\/mastering-css-essential-concepts-for-web-design\/try-solving-this-to-better-understand-flexbox\/","og_site_name":"Sankham Technologies","article_modified_time":"2024-11-15T17:32:37+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sankhamtech.com\/index.php\/content\/in\/en\/home\/free-courses\/mastering-css-essential-concepts-for-web-design\/try-solving-this-to-better-understand-flexbox\/","url":"https:\/\/sankhamtech.com\/index.php\/content\/in\/en\/home\/free-courses\/mastering-css-essential-concepts-for-web-design\/try-solving-this-to-better-understand-flexbox\/","name":"Try Solving This to Better Understand FLEXBOX - Sankham Technologies","isPartOf":{"@id":"https:\/\/sankhamtech.com\/#website"},"datePublished":"2024-11-15T17:31:52+00:00","dateModified":"2024-11-15T17:32:37+00:00","breadcrumb":{"@id":"https:\/\/sankhamtech.com\/index.php\/content\/in\/en\/home\/free-courses\/mastering-css-essential-concepts-for-web-design\/try-solving-this-to-better-understand-flexbox\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sankhamtech.com\/index.php\/content\/in\/en\/home\/free-courses\/mastering-css-essential-concepts-for-web-design\/try-solving-this-to-better-understand-flexbox\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/sankhamtech.com\/index.php\/content\/in\/en\/home\/free-courses\/mastering-css-essential-concepts-for-web-design\/try-solving-this-to-better-understand-flexbox\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sankhamtech.com\/"},{"@type":"ListItem","position":2,"name":"Content","item":"https:\/\/sankhamtech.com\/index.php\/content\/"},{"@type":"ListItem","position":3,"name":"India","item":"https:\/\/sankhamtech.com\/index.php\/content\/in\/"},{"@type":"ListItem","position":4,"name":"English","item":"https:\/\/sankhamtech.com\/index.php\/content\/in\/en\/"},{"@type":"ListItem","position":5,"name":"Home","item":"https:\/\/sankhamtech.com\/"},{"@type":"ListItem","position":6,"name":"Free Courses","item":"https:\/\/sankhamtech.com\/index.php\/content\/in\/en\/home\/free-courses\/"},{"@type":"ListItem","position":7,"name":"Mastering CSS: Essential Concepts for Web Design","item":"https:\/\/sankhamtech.com\/indexphp\/content\/in\/en\/home\/free-courses\/mastering-css-essential-concepts-for-web-design\/"},{"@type":"ListItem","position":8,"name":"Try Solving This to Better Understand FLEXBOX"}]},{"@type":"WebSite","@id":"https:\/\/sankhamtech.com\/#website","url":"https:\/\/sankhamtech.com\/","name":"Sankham Technologies","description":"","publisher":{"@id":"https:\/\/sankhamtech.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sankhamtech.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/sankhamtech.com\/#organization","name":"Sankham Technologies","url":"https:\/\/sankhamtech.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/sankhamtech.com\/#\/schema\/logo\/image\/","url":"https:\/\/sankhamtech.com\/wp-content\/uploads\/2023\/12\/Logo-Dark-1.png","contentUrl":"https:\/\/sankhamtech.com\/wp-content\/uploads\/2023\/12\/Logo-Dark-1.png","width":306,"height":74,"caption":"Sankham Technologies"},"image":{"@id":"https:\/\/sankhamtech.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/sankhamtech.com\/index.php\/wp-json\/wp\/v2\/pages\/3506","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sankhamtech.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/sankhamtech.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/sankhamtech.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sankhamtech.com\/index.php\/wp-json\/wp\/v2\/comments?post=3506"}],"version-history":[{"count":4,"href":"https:\/\/sankhamtech.com\/index.php\/wp-json\/wp\/v2\/pages\/3506\/revisions"}],"predecessor-version":[{"id":3510,"href":"https:\/\/sankhamtech.com\/index.php\/wp-json\/wp\/v2\/pages\/3506\/revisions\/3510"}],"up":[{"embeddable":true,"href":"https:\/\/sankhamtech.com\/index.php\/wp-json\/wp\/v2\/pages\/3442"}],"wp:attachment":[{"href":"https:\/\/sankhamtech.com\/index.php\/wp-json\/wp\/v2\/media?parent=3506"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}